{"id":6708,"date":"2025-08-29T08:28:18","date_gmt":"2025-08-29T08:28:18","guid":{"rendered":"https:\/\/kokashita.fr\/?page_id=6708"},"modified":"2026-05-12T09:54:14","modified_gmt":"2026-05-12T09:54:14","slug":"carte-restaurant-japonais-paris","status":"publish","type":"page","link":"https:\/\/kokashita.fr\/ja\/carte-restaurant-japonais-paris\/","title":{"rendered":"Nos menus"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6708\" class=\"elementor elementor-6708\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1a26ec e-flex e-con-boxed e-con e-parent\" data-id=\"c1a26ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91a63ea elementor-widget elementor-widget-pt_title\" data-id=\"91a63ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"pt-title-wrap text-center\">\t            <div class=\"pt-subtitle-wrap\"><span class=\"pt-subtitle\">Nos menus japonais, du midi au soir<\/span><\/div>\t            <h4 class=\"pt-title\">\n\t                De l'effervescence du midi \u00e0 la douceur du soir\t            <\/h4>\t            <div class=\"pt-title-text\">\n\t                <p data-path-to-node=\"4\">\u00c0 deux pas des Grands Boulevards, la carte de notre restaurant japonais \u00e0 Paris vit au rythme de vos envies. Le midi, place \u00e0 l\u2019\u00e9quilibre avec nos bentos signatures pr\u00e9par\u00e9s \u00e0 la minute.<\/p><p data-path-to-node=\"4\">En effet, notre Chef se rend chaque matin au march\u00e9 pour s\u00e9lectionner lui-m\u00eame ses produits, garantissant une fra\u00eecheur absolue \u00e0 chaque arrivage. De ce fait, vous d\u00e9couvrirez sur place une ardoise de suggestions vari\u00e9es qui \u00e9volue quotidiennement selon ses trouvailles matinales.<\/p><p data-path-to-node=\"3\">Le soir, l&rsquo;ambiance change : l&rsquo;esprit izakaya s&rsquo;installe avec des cr\u00e9ations nippones \u00e0 partager. Une seule adresse \u00e0 Paris 2, deux moments distincts, mais toujours la m\u00eame qu\u00eate d&rsquo;authenticit\u00e9 et de partage.<\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b52231 e-flex e-con-boxed e-con e-parent\" data-id=\"4b52231\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1faaa78 elementor-widget elementor-widget-spacer\" data-id=\"1faaa78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20b12f2a elementor-section-height-min-height elementor-section-items-stretch elementor-reverse-mobile elementor-section-boxed elementor-section-height-default\" data-id=\"20b12f2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-48016beb\" data-id=\"48016beb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cad57e1 elementor-widget elementor-widget-pt_title\" data-id=\"6cad57e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"pt-title-wrap\">\t            <div class=\"pt-subtitle-wrap\"><span class=\"pt-subtitle\">l'art du bento, de Tokyo \u00e0 Paris<\/span><\/div>\t            <h4 class=\"pt-title\">\n\t                Le D\u00e9jeuner chez Kokashita\t            <\/h4>\t            <div class=\"pt-title-text\">\n\t                <p data-path-to-node=\"3\">Au Japon, le bento est bien plus qu\u2019un repas nomade : c\u2019est un art de vivre qui rythme le quotidien.<\/p><p data-path-to-node=\"3\">Chez Kokashita, nous respectons scrupuleusement ce rituel en proposant nos cr\u00e9ations exclusivement au d\u00e9jeuner. Ce choix garantit l&rsquo;authenticit\u00e9 de l&rsquo;exp\u00e9rience et une fra\u00eecheur absolue des produits.<\/p><p data-path-to-node=\"4\">Chaque bento est pr\u00e9par\u00e9 avec une attention m\u00e9ticuleuse, fid\u00e8le \u00e0 l\u2019\u00e9quilibre nippon entre couleurs, textures et saveurs.\u00a0<\/p><p data-path-to-node=\"5\">S\u2019offrir un bento chez Kokashita, c\u2019est s\u2019accorder une parenth\u00e8se raffin\u00e9e au c\u0153ur du Passage des panoramas. C\u2019est la promesse d\u2019un repas complet, sain et esth\u00e9tique, con\u00e7u pour les gourmets en qu\u00eate d\u2019un d\u00e9paysement authentique.<\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68e5c081 elementor-widget__width-auto elementor-widget elementor-widget-pt_button\" data-id=\"68e5c081\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <a href=\"https:\/\/kokashita.fr\/ja\/bento-japonais-midi-kokashita\/\" class=\"elementor-button-link button pt-btn-outline pt-btn-pill\" role=\"button\">\n            <span class=\"pt-btn-text\">C\u00f4t\u00e9 Bento<\/span>\n        <\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5f991a24\" data-id=\"5f991a24\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37f61a32 elementor-widget elementor-widget-spacer\" data-id=\"37f61a32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12622689 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"12622689\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a4e4fdd\" data-id=\"5a4e4fdd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-217509c elementor-widget elementor-widget-spacer\" data-id=\"217509c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4c5cc197\" data-id=\"4c5cc197\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-496ac6f0 elementor-widget elementor-widget-pt_title\" data-id=\"496ac6f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"pt-title-wrap\">\t            <div class=\"pt-subtitle-wrap\"><span class=\"pt-subtitle\">Kokashita Night Fever<\/span><\/div>\t            <h4 class=\"pt-title\">\n\t                Petites assiettes, grandes \u00e9motions.\t            <\/h4>\t            <div class=\"pt-title-text\">\n\t                <p>Une fois la nuit tomb\u00e9e, Kokashita se m\u00e9tamorphose pour adopter les codes de l\u2019izakaya traditionnel, ce bistrot japonais o\u00f9 la convivialit\u00e9 est reine.<\/p><p>Oubliez les codes guind\u00e9s : ici, l&rsquo;ambiance est au partage et \u00e0 la d\u00e9couverte. Notre carte du soir fait la part belle aux tapas japonaises, des petites assiettes cr\u00e9atives con\u00e7ues pour \u00eatre d\u00e9gust\u00e9es ensemble, au rythme de vos envies.<\/p><p>Chaque soir, notre chef laisse libre cours \u00e0 son inspiration avec des suggestions bas\u00e9es sur les meilleurs produits du jour. Vous y retrouverez des classiques revisit\u00e9s et des cr\u00e9ations originales.<\/p><p>Pour sublimer ces mets, nous avons s\u00e9lectionn\u00e9 avec soin une gamme de sak\u00e9s et de sours japonais rafra\u00eechissants.<\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48d88674 elementor-widget__width-auto elementor-widget elementor-widget-pt_button\" data-id=\"48d88674\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <a href=\"https:\/\/kokashita.fr\/ja\/tapas-japonaises-a-partager\/\" class=\"elementor-button-link button pt-btn-outline pt-btn-pill\" role=\"button\">\n            <span class=\"pt-btn-text\">C\u00f4t\u00e9 Tapas<\/span>\n        <\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-7690462 e-flex e-con-boxed e-con e-parent\" data-id=\"7690462\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7dee2fc elementor-widget elementor-widget-spacer\" data-id=\"7dee2fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be2d8c5 elementor-widget elementor-widget-pt_title\" data-id=\"be2d8c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"pt-title-wrap text-center\">\t            <div class=\"pt-subtitle-wrap\"><span class=\"pt-subtitle\">On se retrouve au Sentier ?<\/span><\/div>\t            <h4 class=\"pt-title\">\n\t                Votre escale japonaise\t            <\/h4>\t            <div class=\"pt-title-text\">\n\t                <p>Kokashita vous attend \u00e0 deux pas des Grands Boulevards pour une immersion japonaise authentique. Que ce soit pour attraper un bento frais \u00e0 midi ou partager nos tapas \u00e0 la nuit tomb\u00e9e, notre porte est ouverte. On vous laisse l&rsquo;itin\u00e9raire juste ici pour nous rejoindre au c\u0153ur du 2\u00e8me arrondissement.<\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9014128 e-flex e-con-boxed e-con e-parent\" data-id=\"9014128\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e12392 elementor-widget elementor-widget-spacer\" data-id=\"7e12392\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b616cc4 e-flex e-con-boxed e-con e-parent\" data-id=\"b616cc4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8088bbd elementor-widget elementor-widget-google_maps\" data-id=\"8088bbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=kokashita%2C%2064%20passage%20des%20panoramas%2C%2075002&#038;t=m&#038;z=16&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"kokashita, 64 passage des panoramas, 75002\"\n\t\t\t\t\taria-label=\"kokashita, 64 passage des panoramas, 75002\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nos menus japonais, du midi au soir De l&rsquo;effervescence du midi \u00e0 la douceur du soir \u00c0 deux pas des Grands Boulevards, la carte de notre restaurant japonais \u00e0 Paris vit au rythme de vos envies. Le midi, place \u00e0 l\u2019\u00e9quilibre avec nos bentos signatures pr\u00e9par\u00e9s \u00e0 la minute. En effet, notre Chef se rend chaque matin au march\u00e9 pour s\u00e9lectionner lui-m\u00eame ses produits, garantissant une fra\u00eecheur absolue \u00e0 chaque arrivage. De ce fait, vous d\u00e9couvrirez sur place une ardoise de suggestions vari\u00e9es qui \u00e9volue quotidiennement selon ses trouvailles matinales. Le soir, l&rsquo;ambiance change : l&rsquo;esprit izakaya s&rsquo;installe avec des cr\u00e9ations nippones \u00e0 partager. Une seule adresse \u00e0 Paris 2, &#8230;<\/p>","protected":false},"author":1,"featured_media":8340,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"template-wide-content.php","meta":{"inline_featured_image":false,"patiotime_single_page_hide_site_header":"","patiotime_single_page_site_header_source":"","patiotime_single_page_custom_site_header":"","patiotime_single_page_custom_sticky_site_header":"","patiotime_single_page_custom_page_title_margin_top_source":"","patiotime_single_page_custom_page_title_desktop_margin_top":"","patiotime_single_page_custom_page_title_tablet_margin_top":"","patiotime_single_page_custom_page_title_mobile_margin_top":"","patiotime_single_page_hide_page_title":"","patiotime_single_page_header_section_size":"","patiotime_single_page_header_background_color":"","patiotime_single_page_header_background_position_x":"center","patiotime_single_page_header_background_position_y":"center","patiotime_single_page_header_background_size":"cover","patiotime_single_page_header_background_repeat":"off","patiotime_single_page_header_background_scroll":"on","patiotime_single_page_header_text_color":"","patiotime_single_page_header_show_breadcrumb":"","patiotime_single_page_site_footer_hide_main":"","patiotime_single_custom_site_footer_main_source":"","patiotime_single_custom_site_footer_main":"","patiotime_single_page_site_footer_hide_above":"","patiotime_single_custom_site_footer_above_source":"","patiotime_single_custom_site_footer_above":"","patiotime_single_page_site_footer_hide_instagram":"","patiotime_single_page_site_footer_hide_bottom":"","patiotime_single_custom_mobile_menu_source":"","patiotime_single_custom_mobile_menu":"","patiotime_single_custom_mobile_menu_animation":"","patiotime_single_custom_mobile_menu_width":"","patiotime_single_custom_mobile_menu_custom_width":375,"footnotes":""},"class_list":["post-6708","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carte restaurant japonais Paris<\/title>\n<meta name=\"description\" content=\"Consultez la carte du restaurant japonais Kokashita \u00e0 Paris 2 : cuisine japonaise authentique, bentos et plats \u00e0 partager midi et soir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kokashita.fr\/ja\/carte-restaurant-japonais-paris\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carte restaurant japonais Paris\" \/>\n<meta property=\"og:description\" content=\"Consultez la carte du restaurant japonais Kokashita \u00e0 Paris 2 : cuisine japonaise authentique, bentos et plats \u00e0 partager midi et soir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kokashita.fr\/ja\/carte-restaurant-japonais-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"kokashita\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T09:54:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/IMG_4448-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/carte-restaurant-japonais-paris\\\/\",\"url\":\"https:\\\/\\\/kokashita.fr\\\/carte-restaurant-japonais-paris\\\/\",\"name\":\"Carte restaurant japonais Paris\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/carte-restaurant-japonais-paris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/carte-restaurant-japonais-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kokashita.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_4448-1-scaled.jpg\",\"datePublished\":\"2025-08-29T08:28:18+00:00\",\"dateModified\":\"2026-05-12T09:54:14+00:00\",\"description\":\"Consultez la carte du restaurant japonais Kokashita \u00e0 Paris 2 : cuisine japonaise authentique, bentos et plats \u00e0 partager midi et soir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/carte-restaurant-japonais-paris\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kokashita.fr\\\/carte-restaurant-japonais-paris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/carte-restaurant-japonais-paris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kokashita.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_4448-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/kokashita.fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/IMG_4448-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/carte-restaurant-japonais-paris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/kokashita.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos menus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#website\",\"url\":\"https:\\\/\\\/kokashita.fr\\\/\",\"name\":\"kokashita\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kokashita.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#organization\",\"name\":\"kokashita\",\"url\":\"https:\\\/\\\/kokashita.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kokashita.fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-Logo-Kokashita-4.png\",\"contentUrl\":\"https:\\\/\\\/kokashita.fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-Logo-Kokashita-4.png\",\"width\":500,\"height\":500,\"caption\":\"kokashita\"},\"image\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carte restaurant japonais Paris","description":"Consultez la carte du restaurant japonais Kokashita \u00e0 Paris 2 : cuisine japonaise authentique, bentos et plats \u00e0 partager midi et soir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kokashita.fr\/ja\/carte-restaurant-japonais-paris\/","og_locale":"ja_JP","og_type":"article","og_title":"Carte restaurant japonais Paris","og_description":"Consultez la carte du restaurant japonais Kokashita \u00e0 Paris 2 : cuisine japonaise authentique, bentos et plats \u00e0 partager midi et soir.","og_url":"https:\/\/kokashita.fr\/ja\/carte-restaurant-japonais-paris\/","og_site_name":"kokashita","article_modified_time":"2026-05-12T09:54:14+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/IMG_4448-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"3\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kokashita.fr\/carte-restaurant-japonais-paris\/","url":"https:\/\/kokashita.fr\/carte-restaurant-japonais-paris\/","name":"Carte restaurant japonais Paris","isPartOf":{"@id":"https:\/\/kokashita.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kokashita.fr\/carte-restaurant-japonais-paris\/#primaryimage"},"image":{"@id":"https:\/\/kokashita.fr\/carte-restaurant-japonais-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/IMG_4448-1-scaled.jpg","datePublished":"2025-08-29T08:28:18+00:00","dateModified":"2026-05-12T09:54:14+00:00","description":"Consultez la carte du restaurant japonais Kokashita \u00e0 Paris 2 : cuisine japonaise authentique, bentos et plats \u00e0 partager midi et soir.","breadcrumb":{"@id":"https:\/\/kokashita.fr\/carte-restaurant-japonais-paris\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kokashita.fr\/carte-restaurant-japonais-paris\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/kokashita.fr\/carte-restaurant-japonais-paris\/#primaryimage","url":"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/IMG_4448-1-scaled.jpg","contentUrl":"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/IMG_4448-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/kokashita.fr\/carte-restaurant-japonais-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/kokashita.fr\/"},{"@type":"ListItem","position":2,"name":"Nos menus"}]},{"@type":"WebSite","@id":"https:\/\/kokashita.fr\/#website","url":"https:\/\/kokashita.fr\/","name":"kokashita","description":"","publisher":{"@id":"https:\/\/kokashita.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kokashita.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/kokashita.fr\/#organization","name":"kokashita","url":"https:\/\/kokashita.fr\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/kokashita.fr\/#\/schema\/logo\/image\/","url":"https:\/\/kokashita.fr\/wp-content\/uploads\/2022\/03\/cropped-Logo-Kokashita-4.png","contentUrl":"https:\/\/kokashita.fr\/wp-content\/uploads\/2022\/03\/cropped-Logo-Kokashita-4.png","width":500,"height":500,"caption":"kokashita"},"image":{"@id":"https:\/\/kokashita.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kokashita.fr\/ja\/wp-json\/wp\/v2\/pages\/6708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kokashita.fr\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kokashita.fr\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kokashita.fr\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kokashita.fr\/ja\/wp-json\/wp\/v2\/comments?post=6708"}],"version-history":[{"count":100,"href":"https:\/\/kokashita.fr\/ja\/wp-json\/wp\/v2\/pages\/6708\/revisions"}],"predecessor-version":[{"id":8381,"href":"https:\/\/kokashita.fr\/ja\/wp-json\/wp\/v2\/pages\/6708\/revisions\/8381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kokashita.fr\/ja\/wp-json\/wp\/v2\/media\/8340"}],"wp:attachment":[{"href":"https:\/\/kokashita.fr\/ja\/wp-json\/wp\/v2\/media?parent=6708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}