{"id":6913,"date":"2025-09-05T06:40:29","date_gmt":"2025-09-05T06:40:29","guid":{"rendered":"https:\/\/kokashita.fr\/?page_id=6913"},"modified":"2026-05-12T09:47:48","modified_gmt":"2026-05-12T09:47:48","slug":"bento-japonais-midi-kokashita","status":"publish","type":"page","link":"https:\/\/kokashita.fr\/es\/bento-japonais-midi-kokashita\/","title":{"rendered":"Bentos"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6913\" class=\"elementor elementor-6913\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d281cf6 e-flex e-con-boxed e-con e-parent\" data-id=\"d281cf6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-130e3d1 elementor-widget elementor-widget-pt_title\" data-id=\"130e3d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"pt-title-wrap text-center\">\t            <div class=\"pt-subtitle-wrap\"><span class=\"pt-subtitle\">Menu BENTO MIDI<\/span><\/div>\t            <div class=\"pt-title-text\">\n\t                <p>D\u00e9couvrez notre menu bento japonais, disponible lors des d\u00e9jeuners du mardi au vendredi.<\/p><p>Chaque matin, le Chef compose \u00e9galement une carte de suggestions au gr\u00e9 des produits frais d\u00e9nich\u00e9s au march\u00e9. Pour vous offrir une exp\u00e9rience compl\u00e8te et \u00e9quilibr\u00e9e, l&rsquo;ensemble de nos plats sont servis avec tous les accompagnements traditionnels pr\u00e9sent\u00e9s ci-dessous.<\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2ff841 elementor-widget elementor-widget-spacer\" data-id=\"b2ff841\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e693247 elementor-widget elementor-widget-pt_title\" data-id=\"e693247\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"pt-title-wrap text-left\">\t            <h5 class=\"pt-title\">\n\t                NOS BENTOS - \u304a\u5f01\u5f53\t            <\/h5>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-675fa37 elementor-widget elementor-widget-spacer\" data-id=\"675fa37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fdb2c2f e-grid e-con-boxed e-con e-parent\" data-id=\"fdb2c2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e75358f elementor-widget elementor-widget-pt_food_card\" data-id=\"e75358f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"pt-food-card\">\t            <div class=\"pt-fc-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-scaled.jpg\" class=\"attachment-full size-full wp-image-7594\" alt=\"bento l\u00e9gumes saut\u00e9s\" srcset=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-scaled.jpg 1707w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-200x300.jpg 200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-683x1024.jpg 683w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-768x1152.jpg 768w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-1024x1536.jpg 1024w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-1365x2048.jpg 1365w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-8x12.jpg 8w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-1920x2880.jpg 1920w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-1440x2160.jpg 1440w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-1200x1800.jpg 1200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-780x1170.jpg 780w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-600x900.jpg 600w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-550x825.jpg 550w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-370x555.jpg 370w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4272-255x383.jpg 255w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/div>            <div class=\"pt-fc-info\">\n                <div class=\"pt-fc-info-wrap\">                    <h2 class=\"pt-fc-info-title\">L\u00e9gumes saut\u00e9s \u91ce\u83dc\u7092\u3081<\/h2>                    <div class=\"pt-fc-info-text\"><p>Assortiment de l\u00e9gumes de saison saut\u00e9s au wok, l\u00e9g\u00e8rement assaisonn\u00e9s \u00e0 la sauce soja.<\/p><\/div>\t                    <div class=\"pt-fc-info-extra\">\t                        <span class=\"info-content\">14\u20ac<\/span>\t\t\t\t\t\t<\/div>                <\/div>\n            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-956e909 elementor-widget elementor-widget-pt_food_card\" data-id=\"956e909\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"pt-food-card\">\t            <div class=\"pt-fc-img\"><img decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-scaled.jpg\" class=\"attachment-full size-full wp-image-7595\" alt=\"bento karaage (poulet frit)\" srcset=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-scaled.jpg 1707w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-200x300.jpg 200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-683x1024.jpg 683w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-768x1152.jpg 768w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-1024x1536.jpg 1024w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-1365x2048.jpg 1365w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-8x12.jpg 8w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-1920x2880.jpg 1920w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-1440x2160.jpg 1440w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-1200x1800.jpg 1200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-780x1170.jpg 780w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-600x900.jpg 600w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-550x825.jpg 550w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-370x555.jpg 370w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4265-255x383.jpg 255w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/div>            <div class=\"pt-fc-info\">\n                <div class=\"pt-fc-info-wrap\">                    <h2 class=\"pt-fc-info-title\">Karaage \u9d8f\u306e\u7adc\u7530\u63da\u3052<\/h2>                    <div class=\"pt-fc-info-text\"><p>Poulet marin\u00e9 au gingembre, frit, croustillant, servi avec du citron frais.<\/p><\/div>\t                    <div class=\"pt-fc-info-extra\">\t                        <span class=\"info-content\">15\u20ac<\/span>\t\t\t\t\t\t<\/div>                <\/div>\n            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96504e7 elementor-widget elementor-widget-pt_food_card\" data-id=\"96504e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"pt-food-card\">\t            <div class=\"pt-fc-img\"><img decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-scaled.jpg\" class=\"attachment-full size-full wp-image-7597\" alt=\"\" srcset=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-scaled.jpg 1707w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-200x300.jpg 200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-683x1024.jpg 683w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-768x1152.jpg 768w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-1024x1536.jpg 1024w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-1365x2048.jpg 1365w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-8x12.jpg 8w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-1920x2880.jpg 1920w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-1440x2160.jpg 1440w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-1200x1800.jpg 1200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-780x1170.jpg 780w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-600x900.jpg 600w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-550x825.jpg 550w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-370x555.jpg 370w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4254-255x383.jpg 255w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/div>            <div class=\"pt-fc-info\">\n                <div class=\"pt-fc-info-wrap\">                    <h4 class=\"pt-fc-info-title\">Steak hach\u00e9 mijot\u00e9 \u716e\u8fbc\u307f\u30cf\u30f3\u30d0\u30fc\u30b0<\/h4>                    <div class=\"pt-fc-info-text\"><p>Steak hach\u00e9 tendre mijot\u00e9 dans une sauce brune japonaise, napp\u00e9 de son jus.<\/p><\/div>\t                    <div class=\"pt-fc-info-extra\">\t                        <span class=\"info-content\">16\u20ac<\/span>\t\t\t\t\t\t<\/div>                <\/div>\n            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f72dc86 elementor-widget elementor-widget-pt_food_card\" data-id=\"f72dc86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"pt-food-card\">\t            <div class=\"pt-fc-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-scaled.jpg\" class=\"attachment-full size-full wp-image-7598\" alt=\"\" srcset=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-scaled.jpg 1707w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-200x300.jpg 200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-683x1024.jpg 683w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-768x1152.jpg 768w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-1024x1536.jpg 1024w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-1365x2048.jpg 1365w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-8x12.jpg 8w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-1920x2880.jpg 1920w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-1440x2160.jpg 1440w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-1200x1800.jpg 1200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-780x1170.jpg 780w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-600x900.jpg 600w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-550x825.jpg 550w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-370x555.jpg 370w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4249-255x383.jpg 255w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/div>            <div class=\"pt-fc-info\">\n                <div class=\"pt-fc-info-wrap\">                    <h4 class=\"pt-fc-info-title\">Maquereau sal\u00e9 grill\u00e9 \u9bd6\u306e\u5869\u713c\u304d<\/h4>                    <div class=\"pt-fc-info-text\"><p>Filet de maquereau sal\u00e9 grill\u00e9, servi avec citron et daikon r\u00e2p\u00e9.<\/p><\/div>\t                    <div class=\"pt-fc-info-extra\">\t                        <span class=\"info-content\">17\u20ac<\/span>\t\t\t\t\t\t<\/div>                <\/div>\n            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-520e011 elementor-widget elementor-widget-pt_food_card\" data-id=\"520e011\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"pt-food-card\">\t            <div class=\"pt-fc-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-scaled.jpg\" class=\"attachment-full size-full wp-image-8319\" alt=\"\" srcset=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-scaled.jpg 1707w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-200x300.jpg 200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-683x1024.jpg 683w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-768x1152.jpg 768w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-1024x1536.jpg 1024w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-1365x2048.jpg 1365w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-8x12.jpg 8w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-1920x2880.jpg 1920w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-1440x2160.jpg 1440w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-1200x1800.jpg 1200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-780x1170.jpg 780w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-600x900.jpg 600w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-550x825.jpg 550w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-370x555.jpg 370w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Bento-mixte-4-1-255x383.jpg 255w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/div>            <div class=\"pt-fc-info\">\n                <div class=\"pt-fc-info-wrap\">                    <h4 class=\"pt-fc-info-title\">Mixte \u30df\u30c3\u30af\u30b9\u5f01\u5f53\u3000<\/h4>                    <div class=\"pt-fc-info-text\"><p>Karaage, steak hanch\u00e9 tendre mijot\u00e9, tempura de crevette le tout accompagn\u00e9 d'un bol de riz blanc.<\/p><\/div>\t                    <div class=\"pt-fc-info-extra\">\t                        <span class=\"info-content\">17\u20ac<\/span>\t\t\t\t\t\t<\/div>                <\/div>\n            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-287e347 e-flex e-con-boxed e-con e-parent\" data-id=\"287e347\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-932c0a5 elementor-widget elementor-widget-spacer\" data-id=\"932c0a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e71913f e-flex e-con-boxed e-con e-parent\" data-id=\"e71913f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e86bc7d elementor-widget elementor-widget-pt_title\" data-id=\"e86bc7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"pt-title-wrap text-left\">\t            <h5 class=\"pt-title\">\n\t                NOS ACCOMPAGNEMENTS - \u304a\u5f01\u5f53\u5185\u5bb9\t            <\/h5>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0233d22 elementor-widget elementor-widget-spacer\" data-id=\"0233d22\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d89c68 elementor-widget elementor-widget-pt_food_menu\" data-id=\"4d89c68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"pt-food-menu food-menu-style-1\">                <div class=\"pt-food-menu-item\">                    <div class=\"pt-food-menu-main\">\n                        <div class=\"pt-food-menu-header\">                            <h6 class=\"pt-food-menu-title\">                                <span class=\"title-wrap\">Omelette japonaise \u7389\u5b50\u713c\u304d\t\t\t\t\t\t\t\t<\/span>                            <\/h6>\n                            <div class=\"pt-food-menu-lines\"><\/div>                        <\/div>                            <p class=\"pt-food-menu-details\">Omelette japonaise roul\u00e9e, moelleuse et d\u00e9licatement sucr\u00e9e, \u00e0 la texture fondante.<\/p>                    <\/div>\n                <\/div>                <div class=\"pt-food-menu-item\">                    <div class=\"pt-food-menu-main\">\n                        <div class=\"pt-food-menu-header\">                            <h6 class=\"pt-food-menu-title\">                                <span class=\"title-wrap\">Salade de pommes de terre \u30dd\u30c6\u30b5\u30e9\t\t\t\t\t\t\t\t<\/span>                            <\/h6>\n                            <div class=\"pt-food-menu-lines\"><\/div>                        <\/div>                            <p class=\"pt-food-menu-details\">Salade de pommes de terre japonaise, g\u00e9n\u00e9reusement li\u00e9e \u00e0 la mayonnaise.<\/p>                    <\/div>\n                <\/div>                <div class=\"pt-food-menu-item\">                    <div class=\"pt-food-menu-main\">\n                        <div class=\"pt-food-menu-header\">                            <h6 class=\"pt-food-menu-title\">                                <span class=\"title-wrap\">Aubergines mijot\u00e9es \u8304\u5b50\u7530\u697d\t\t\t\t\t\t\t\t<\/span>                            <\/h6>\n                            <div class=\"pt-food-menu-lines\"><\/div>                        <\/div>                            <p class=\"pt-food-menu-details\">Tranches fondantes longuement mijot\u00e9es, d\u00e9licatement parfum\u00e9es.<\/p>                    <\/div>\n                <\/div>                <div class=\"pt-food-menu-item\">                    <div class=\"pt-food-menu-main\">\n                        <div class=\"pt-food-menu-header\">                            <h6 class=\"pt-food-menu-title\">                                <span class=\"title-wrap\">Carottes saut\u00e9es \u4eba\u53c2\u306e\u91d1\u5e73\t\t\t\t\t\t\t\t<\/span>                            <\/h6>\n                            <div class=\"pt-food-menu-lines\"><\/div>                        <\/div>                            <p class=\"pt-food-menu-details\">Carottes croquantes, assaisonnement l\u00e9ger.<\/p>                    <\/div>\n                <\/div>                <div class=\"pt-food-menu-item\">                    <div class=\"pt-food-menu-main\">\n                        <div class=\"pt-food-menu-header\">                            <h6 class=\"pt-food-menu-title\">                                <span class=\"title-wrap\">Haricots verts au s\u00e9same \u3044\u3093\u3052\u3093\u306e\u80e1\u9ebb\u548c\u3048\t\t\t\t\t\t\t\t<\/span>                            <\/h6>\n                            <div class=\"pt-food-menu-lines\"><\/div>                        <\/div>                            <p class=\"pt-food-menu-details\">Haricots frais et croquants, enrob\u00e9s d'une sauce onctueuse au s\u00e9same<\/p>                    <\/div>\n                <\/div>                <div class=\"pt-food-menu-item\">                    <div class=\"pt-food-menu-main\">\n                        <div class=\"pt-food-menu-header\">                            <h6 class=\"pt-food-menu-title\">                                <span class=\"title-wrap\">Padron marin\u00e9 \u3057\u3057\u3068\u3046\u306e\u63da\u3052\u6d78\u3057\t\t\t\t\t\t\t\t<\/span>                            <\/h6>\n                            <div class=\"pt-food-menu-lines\"><\/div>                        <\/div>                            <p class=\"pt-food-menu-details\">Petits poivrons Padr\u00f3n, marin\u00e9s et l\u00e9g\u00e8rement grill\u00e9s.<\/p>                    <\/div>\n                <\/div>                <div class=\"pt-food-menu-item\">                    <div class=\"pt-food-menu-main\">\n                        <div class=\"pt-food-menu-header\">                            <h6 class=\"pt-food-menu-title\">                                <span class=\"title-wrap\">Tsukemono \u2013 L\u00e9gumes marin\u00e9s \u6f2c\u7269\t\t\t\t\t\t\t\t<\/span>                            <\/h6>\n                            <div class=\"pt-food-menu-lines\"><\/div>                        <\/div>                            <p class=\"pt-food-menu-details\">Pickles japonais croquants et acidul\u00e9s,<\/p>                    <\/div>\n                <\/div>                <div class=\"pt-food-menu-item\">                    <div class=\"pt-food-menu-main\">\n                        <div class=\"pt-food-menu-header\">                            <h6 class=\"pt-food-menu-title\">                                <span class=\"title-wrap\">Spaghetti \u00e0 l'ail fa\u00e7on japonaise \u30ac\u30fc\u30ea\u30c3\u30af\u30b9\u30d1\u30b2\u30c3\u30c6\u30a3\t\t\t\t\t\t\t\t<\/span>                            <\/h6>\n                            <div class=\"pt-food-menu-lines\"><\/div>                        <\/div>                            <p class=\"pt-food-menu-details\">Spaghetti \u00e0 l\u2019ail, fa\u00e7on japonaise, relev\u00e9s et d\u00e9licatement parfum\u00e9s.<\/p>                    <\/div>\n                <\/div>                <div class=\"pt-food-menu-item\">                    <div class=\"pt-food-menu-main\">\n                        <div class=\"pt-food-menu-header\">                            <h6 class=\"pt-food-menu-title\">                                <span class=\"title-wrap\">Riz \u3054\u98ef\t\t\t\t\t\t\t\t<\/span>                            <\/h6>\n                            <div class=\"pt-food-menu-lines\"><\/div>                        <\/div>                            <p class=\"pt-food-menu-details\">Riz blanc vapeur, moelleux et l\u00e9ger.<\/p>                    <\/div>\n                <\/div>                <div class=\"pt-food-menu-item\">                    <div class=\"pt-food-menu-main\">\n                        <div class=\"pt-food-menu-header\">                            <h6 class=\"pt-food-menu-title\">                                <span class=\"title-wrap\">Salade \u30b5\u30e9\u30c0\u3000\t\t\t\t\t\t\t\t<\/span>                            <\/h6>\n                            <div class=\"pt-food-menu-lines\"><\/div>                        <\/div>                            <p class=\"pt-food-menu-details\">Salade fra\u00eeche, croquante et l\u00e9g\u00e8re.<\/p>                    <\/div>\n                <\/div>            <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89e7f62 e-flex e-con-boxed e-con e-parent\" data-id=\"89e7f62\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a52338 elementor-widget elementor-widget-spacer\" data-id=\"4a52338\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-194f123 e-flex e-con-boxed e-con e-parent\" data-id=\"194f123\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8319beb elementor-widget elementor-widget-pt_title\" data-id=\"8319beb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"pt-title-wrap text-left\">\t            <h5 class=\"pt-title\">\n\t                NOS SUPPL\u00c9MENTS\t            <\/h5>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed773ec elementor-widget elementor-widget-spacer\" data-id=\"ed773ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4f756ec e-grid e-con-boxed e-con e-parent\" data-id=\"4f756ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbe0a9f elementor-widget elementor-widget-pt_food_card\" data-id=\"bbe0a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"pt-food-card\">\t            <div class=\"pt-fc-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-scaled.jpg\" class=\"attachment-full size-full wp-image-8349\" alt=\"\" srcset=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-scaled.jpg 1707w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-200x300.jpg 200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-683x1024.jpg 683w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-768x1152.jpg 768w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-1024x1536.jpg 1024w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-1365x2048.jpg 1365w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-8x12.jpg 8w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-1920x2880.jpg 1920w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-1440x2160.jpg 1440w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-1200x1800.jpg 1200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-780x1170.jpg 780w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-600x900.jpg 600w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-550x825.jpg 550w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-370x555.jpg 370w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/05\/Soupe-miso-1-255x383.jpg 255w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/div>            <div class=\"pt-fc-info\">\n                <div class=\"pt-fc-info-wrap\">                    <h4 class=\"pt-fc-info-title\">Soupe miso \u5473\u564c\u6c41<\/h4>                    <div class=\"pt-fc-info-text color-black\"><p>Bouillon miso, tofu et algues wakam\u00e9.<\/p><\/div>\t                    <div class=\"pt-fc-info-extra\">\t                        <span class=\"info-content\">2\u20ac<\/span>\t\t\t\t\t\t<\/div>                <\/div>\n            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d911607 elementor-widget elementor-widget-pt_food_card\" data-id=\"d911607\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"pt-food-card\">\t            <div class=\"pt-fc-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-scaled.jpg\" class=\"attachment-full size-full wp-image-7673\" alt=\"\u30ab\u30ec\u30fc\u30e9\u30a4\u30b9\" srcset=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-scaled.jpg 1707w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-200x300.jpg 200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-683x1024.jpg 683w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-768x1152.jpg 768w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-1024x1536.jpg 1024w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-1365x2048.jpg 1365w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-8x12.jpg 8w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-1920x2880.jpg 1920w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-1440x2160.jpg 1440w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-1200x1800.jpg 1200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-780x1170.jpg 780w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-600x900.jpg 600w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-550x825.jpg 550w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-370x555.jpg 370w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4293-255x383.jpg 255w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/div>            <div class=\"pt-fc-info\">\n                <div class=\"pt-fc-info-wrap\">                    <h4 class=\"pt-fc-info-title\">Riz blanc \u3054\u98ef<\/h4>                    <div class=\"pt-fc-info-text\"><p>Riz rond cuit \u00e0 la vapeur, tendre et parfum\u00e9.<\/p><\/div>\t                    <div class=\"pt-fc-info-extra\">\t                        <span class=\"info-content\">2\u20ac<\/span>\t\t\t\t\t\t<\/div>                <\/div>\n            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9e36c5 elementor-widget elementor-widget-pt_food_card\" data-id=\"e9e36c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"pt-food-card\">\t            <div class=\"pt-fc-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-scaled.jpg\" class=\"attachment-full size-full wp-image-7659\" alt=\"edamame\" srcset=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-scaled.jpg 1707w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-200x300.jpg 200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-683x1024.jpg 683w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-768x1152.jpg 768w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-1024x1536.jpg 1024w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-1365x2048.jpg 1365w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-8x12.jpg 8w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-1920x2880.jpg 1920w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-1440x2160.jpg 1440w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-1200x1800.jpg 1200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-780x1170.jpg 780w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-600x900.jpg 600w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-550x825.jpg 550w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-370x555.jpg 370w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4279-255x383.jpg 255w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/div>            <div class=\"pt-fc-info\">\n                <div class=\"pt-fc-info-wrap\">                    <h2 class=\"pt-fc-info-title\">Edamame \u679d\u8c46<\/h2>                    <div class=\"pt-fc-info-text\"><p>F\u00e8ves de soja l\u00e9g\u00e8rement sal\u00e9es<\/p><\/div>\t                    <div class=\"pt-fc-info-extra\">\t                        <span class=\"info-content\">3\u20ac<\/span>\t\t\t\t\t\t<\/div>                <\/div>\n            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4d3489 elementor-widget elementor-widget-pt_food_card\" data-id=\"f4d3489\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"pt-food-card\">\t            <div class=\"pt-fc-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-scaled.jpg\" class=\"attachment-full size-full wp-image-7631\" alt=\"\" srcset=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-scaled.jpg 1707w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-200x300.jpg 200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-683x1024.jpg 683w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-768x1152.jpg 768w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-1024x1536.jpg 1024w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-1365x2048.jpg 1365w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-8x12.jpg 8w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-1920x2880.jpg 1920w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-1440x2160.jpg 1440w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-1200x1800.jpg 1200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-780x1170.jpg 780w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-600x900.jpg 600w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-550x825.jpg 550w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-370x555.jpg 370w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4251-255x383.jpg 255w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/div>            <div class=\"pt-fc-info\">\n                <div class=\"pt-fc-info-wrap\">                    <h2 class=\"pt-fc-info-title\">Karaage 3p - Poulet frit \u9d8f\u306e\u7adc\u7530\u63da\u3052<\/h2>                    <div class=\"pt-fc-info-text\"><p>Poulet frit japonais, croustillant et juteux.<\/p><\/div>\t                    <div class=\"pt-fc-info-extra\">\t                        <span class=\"info-content\">4\u20ac<\/span>\t\t\t\t\t\t<\/div>                <\/div>\n            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-960d36d elementor-widget elementor-widget-pt_food_card\" data-id=\"960d36d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_food_card.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"pt-food-card\">\t            <div class=\"pt-fc-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-scaled.jpg\" class=\"attachment-full size-full wp-image-7640\" alt=\"l\u00e9gumes saut\u00e9s en suppl\u00e9ment\" srcset=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-scaled.jpg 1707w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-200x300.jpg 200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-683x1024.jpg 683w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-768x1152.jpg 768w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-1024x1536.jpg 1024w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-1365x2048.jpg 1365w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-8x12.jpg 8w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-1920x2880.jpg 1920w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-1440x2160.jpg 1440w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-1200x1800.jpg 1200w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-780x1170.jpg 780w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-600x900.jpg 600w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-550x825.jpg 550w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-370x555.jpg 370w, https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4260-255x383.jpg 255w\" sizes=\"(max-width: 1707px) 100vw, 1707px\" \/><\/div>            <div class=\"pt-fc-info\">\n                <div class=\"pt-fc-info-wrap\">                    <h2 class=\"pt-fc-info-title\">L\u00e9gumes saut\u00e9s \u91ce\u83dc\u7092\u3081\u3000<\/h2>                    <div class=\"pt-fc-info-text\"><p>Wok de l\u00e9gumes croquants, saisis \u00e0 la minute.<\/p><\/div>\t                    <div class=\"pt-fc-info-extra\">\t                        <span class=\"info-content\">4\u20ac<\/span>\t\t\t\t\t\t<\/div>                <\/div>\n            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bcf521 e-flex e-con-boxed e-con e-parent\" data-id=\"1bcf521\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fabf501 elementor-widget elementor-widget-spacer\" data-id=\"fabf501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74c84c4 e-flex e-con-boxed e-con e-parent\" data-id=\"74c84c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f73949 elementor-align-center elementor-widget__width-inherit elementor-widget elementor-widget-pt_button\" data-id=\"3f73949\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pt_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <a href=\"https:\/\/kokashita.fr\/es\/reservation-izakaya-kokashita\/\" class=\"elementor-button-link button pt-btn-pill pt-btn-large\" role=\"button\">\n            <span class=\"pt-btn-text\">Je r\u00e9serve <\/span>\n        <\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6f7bf7 elementor-widget elementor-widget-spacer\" data-id=\"f6f7bf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Menu BENTO MIDI D\u00e9couvrez notre menu bento japonais, disponible lors des d\u00e9jeuners du mardi au vendredi. Chaque matin, le Chef compose \u00e9galement une carte de suggestions au gr\u00e9 des produits frais d\u00e9nich\u00e9s au march\u00e9. Pour vous offrir une exp\u00e9rience compl\u00e8te et \u00e9quilibr\u00e9e, l&rsquo;ensemble de nos plats sont servis avec tous les accompagnements traditionnels pr\u00e9sent\u00e9s ci-dessous. &#8230;<\/p>","protected":false},"author":1,"featured_media":7602,"parent":0,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"template-wide-content.php","meta":{"inline_featured_image":false,"patiotime_single_page_hide_site_header":"","patiotime_single_page_site_header_source":"","patiotime_single_page_custom_site_header":"","patiotime_single_page_custom_sticky_site_header":"","patiotime_single_page_custom_page_title_margin_top_source":"","patiotime_single_page_custom_page_title_desktop_margin_top":"","patiotime_single_page_custom_page_title_tablet_margin_top":"","patiotime_single_page_custom_page_title_mobile_margin_top":"","patiotime_single_page_hide_page_title":"","patiotime_single_page_header_section_size":"","patiotime_single_page_header_background_color":"","patiotime_single_page_header_background_position_x":"center","patiotime_single_page_header_background_position_y":"center","patiotime_single_page_header_background_size":"cover","patiotime_single_page_header_background_repeat":"off","patiotime_single_page_header_background_scroll":"on","patiotime_single_page_header_text_color":"","patiotime_single_page_header_show_breadcrumb":"","patiotime_single_page_site_footer_hide_main":"","patiotime_single_custom_site_footer_main_source":"","patiotime_single_custom_site_footer_main":"","patiotime_single_page_site_footer_hide_above":"","patiotime_single_custom_site_footer_above_source":"","patiotime_single_custom_site_footer_above":"","patiotime_single_page_site_footer_hide_instagram":"","patiotime_single_page_site_footer_hide_bottom":"","patiotime_single_custom_mobile_menu_source":"","patiotime_single_custom_mobile_menu":"","patiotime_single_custom_mobile_menu_animation":"","patiotime_single_custom_mobile_menu_width":"","patiotime_single_custom_mobile_menu_custom_width":375,"footnotes":""},"class_list":["post-6913","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kokashita - Nos bentos japonais du midi<\/title>\n<meta name=\"description\" content=\"Savourez le meilleur menu bento japonais de Paris 2 chez Kokashita. Une cuisine japonaise fra\u00eeche, savoureuse et authentique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kokashita.fr\/es\/bento-japonais-midi-kokashita\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kokashita - Nos bentos japonais du midi\" \/>\n<meta property=\"og:description\" content=\"Savourez le meilleur menu bento japonais de Paris 2 chez Kokashita. Une cuisine japonaise fra\u00eeche, savoureuse et authentique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kokashita.fr\/es\/bento-japonais-midi-kokashita\/\" \/>\n<meta property=\"og:site_name\" content=\"kokashita\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T09:47:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4246-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/bento-japonais-midi-kokashita\\\/\",\"url\":\"https:\\\/\\\/kokashita.fr\\\/bento-japonais-midi-kokashita\\\/\",\"name\":\"Kokashita - Nos bentos japonais du midi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/bento-japonais-midi-kokashita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/bento-japonais-midi-kokashita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kokashita.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_4246-scaled.jpg\",\"datePublished\":\"2025-09-05T06:40:29+00:00\",\"dateModified\":\"2026-05-12T09:47:48+00:00\",\"description\":\"Savourez le meilleur menu bento japonais de Paris 2 chez Kokashita. Une cuisine japonaise fra\u00eeche, savoureuse et authentique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/bento-japonais-midi-kokashita\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kokashita.fr\\\/bento-japonais-midi-kokashita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/bento-japonais-midi-kokashita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kokashita.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_4246-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/kokashita.fr\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/IMG_4246-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"zoom sur le bento maquereau grill\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/bento-japonais-midi-kokashita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/kokashita.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#website\",\"url\":\"https:\\\/\\\/kokashita.fr\\\/\",\"name\":\"kokashita\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kokashita.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#organization\",\"name\":\"kokashita\",\"url\":\"https:\\\/\\\/kokashita.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kokashita.fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-Logo-Kokashita-4.png\",\"contentUrl\":\"https:\\\/\\\/kokashita.fr\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cropped-Logo-Kokashita-4.png\",\"width\":500,\"height\":500,\"caption\":\"kokashita\"},\"image\":{\"@id\":\"https:\\\/\\\/kokashita.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kokashita - Nos bentos japonais du midi","description":"Savourez le meilleur menu bento japonais de Paris 2 chez Kokashita. Une cuisine japonaise fra\u00eeche, savoureuse et authentique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kokashita.fr\/es\/bento-japonais-midi-kokashita\/","og_locale":"es_ES","og_type":"article","og_title":"Kokashita - Nos bentos japonais du midi","og_description":"Savourez le meilleur menu bento japonais de Paris 2 chez Kokashita. Une cuisine japonaise fra\u00eeche, savoureuse et authentique.","og_url":"https:\/\/kokashita.fr\/es\/bento-japonais-midi-kokashita\/","og_site_name":"kokashita","article_modified_time":"2026-05-12T09:47:48+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4246-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kokashita.fr\/bento-japonais-midi-kokashita\/","url":"https:\/\/kokashita.fr\/bento-japonais-midi-kokashita\/","name":"Kokashita - Nos bentos japonais du midi","isPartOf":{"@id":"https:\/\/kokashita.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kokashita.fr\/bento-japonais-midi-kokashita\/#primaryimage"},"image":{"@id":"https:\/\/kokashita.fr\/bento-japonais-midi-kokashita\/#primaryimage"},"thumbnailUrl":"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4246-scaled.jpg","datePublished":"2025-09-05T06:40:29+00:00","dateModified":"2026-05-12T09:47:48+00:00","description":"Savourez le meilleur menu bento japonais de Paris 2 chez Kokashita. Une cuisine japonaise fra\u00eeche, savoureuse et authentique.","breadcrumb":{"@id":"https:\/\/kokashita.fr\/bento-japonais-midi-kokashita\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kokashita.fr\/bento-japonais-midi-kokashita\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kokashita.fr\/bento-japonais-midi-kokashita\/#primaryimage","url":"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4246-scaled.jpg","contentUrl":"https:\/\/kokashita.fr\/wp-content\/uploads\/2026\/03\/IMG_4246-scaled.jpg","width":1707,"height":2560,"caption":"zoom sur le bento maquereau grill\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/kokashita.fr\/bento-japonais-midi-kokashita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/kokashita.fr\/"},{"@type":"ListItem","position":2,"name":"Bentos"}]},{"@type":"WebSite","@id":"https:\/\/kokashita.fr\/#website","url":"https:\/\/kokashita.fr\/","name":"kokashita","description":"","publisher":{"@id":"https:\/\/kokashita.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kokashita.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/kokashita.fr\/#organization","name":"kokashita","url":"https:\/\/kokashita.fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kokashita.fr\/#\/schema\/logo\/image\/","url":"https:\/\/kokashita.fr\/wp-content\/uploads\/2022\/03\/cropped-Logo-Kokashita-4.png","contentUrl":"https:\/\/kokashita.fr\/wp-content\/uploads\/2022\/03\/cropped-Logo-Kokashita-4.png","width":500,"height":500,"caption":"kokashita"},"image":{"@id":"https:\/\/kokashita.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kokashita.fr\/es\/wp-json\/wp\/v2\/pages\/6913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kokashita.fr\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kokashita.fr\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kokashita.fr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kokashita.fr\/es\/wp-json\/wp\/v2\/comments?post=6913"}],"version-history":[{"count":131,"href":"https:\/\/kokashita.fr\/es\/wp-json\/wp\/v2\/pages\/6913\/revisions"}],"predecessor-version":[{"id":8369,"href":"https:\/\/kokashita.fr\/es\/wp-json\/wp\/v2\/pages\/6913\/revisions\/8369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kokashita.fr\/es\/wp-json\/wp\/v2\/media\/7602"}],"wp:attachment":[{"href":"https:\/\/kokashita.fr\/es\/wp-json\/wp\/v2\/media?parent=6913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}